{"id":2230,"date":"2025-01-17T18:38:24","date_gmt":"2025-01-17T21:38:24","guid":{"rendered":"https:\/\/upgyn.com.br\/sereno\/?post_type=cardapio&#038;p=2230"},"modified":"2025-09-19T08:57:42","modified_gmt":"2025-09-19T11:57:42","slug":"soda-italiana-de-maca-verde-2","status":"publish","type":"cardapio","link":"https:\/\/upgyn.com.br\/sereno\/cardapio\/soda-italiana-de-maca-verde-2\/","title":{"rendered":"Soda Italiana de Morango"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categoria-delivery":[56,64],"class_list":["post-2230","cardapio","type-cardapio","status-publish","hentry","categoria-delivery-nao-alcoolicas","categoria-delivery-drinks-nao-alcoolicas"],"_links":{"self":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/cardapio\/2230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/cardapio"}],"about":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/types\/cardapio"}],"wp:attachment":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/media?parent=2230"}],"wp:term":[{"taxonomy":"categoria-delivery","embeddable":true,"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/categoria-delivery?post=2230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}