{"id":2080,"date":"2025-01-17T10:24:16","date_gmt":"2025-01-17T13:24:16","guid":{"rendered":"https:\/\/upgyn.com.br\/sereno\/?post_type=cardapio&#038;p=2080"},"modified":"2025-01-17T16:46:51","modified_gmt":"2025-01-17T19:46:51","slug":"johnnie-walker-red-label","status":"publish","type":"cardapio","link":"https:\/\/upgyn.com.br\/sereno\/cardapio\/johnnie-walker-red-label\/","title":{"rendered":"Johnnie Walker Red Label"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categoria-delivery":[53,61],"class_list":["post-2080","cardapio","type-cardapio","status-publish","hentry","categoria-delivery-bebidas-alcoolicas","categoria-delivery-garrafas"],"_links":{"self":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/cardapio\/2080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/cardapio"}],"about":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/types\/cardapio"}],"wp:attachment":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/media?parent=2080"}],"wp:term":[{"taxonomy":"categoria-delivery","embeddable":true,"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/categoria-delivery?post=2080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}