{"id":2065,"date":"2025-01-17T09:19:48","date_gmt":"2025-01-17T12:19:48","guid":{"rendered":"https:\/\/upgyn.com.br\/sereno\/?post_type=cardapio&#038;p=2065"},"modified":"2025-01-17T16:47:27","modified_gmt":"2025-01-17T19:47:27","slug":"tequila-sunrise","status":"publish","type":"cardapio","link":"https:\/\/upgyn.com.br\/sereno\/cardapio\/tequila-sunrise\/","title":{"rendered":"Tequila Sunrise"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categoria-delivery":[53,60],"class_list":["post-2065","cardapio","type-cardapio","status-publish","hentry","categoria-delivery-bebidas-alcoolicas","categoria-delivery-drinks"],"_links":{"self":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/cardapio\/2065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/cardapio"}],"about":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/types\/cardapio"}],"wp:attachment":[{"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/media?parent=2065"}],"wp:term":[{"taxonomy":"categoria-delivery","embeddable":true,"href":"https:\/\/upgyn.com.br\/sereno\/wp-json\/wp\/v2\/categoria-delivery?post=2065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}